{"id":647,"count":6,"description":"","link":"https:\/\/www.hiptravelguide.com\/go\/tag\/st-thomas\/","name":"St Thomas","slug":"st-thomas","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.hiptravelguide.com\/go\/wp-json\/wp\/v2\/tags\/647"}],"collection":[{"href":"https:\/\/www.hiptravelguide.com\/go\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.hiptravelguide.com\/go\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.hiptravelguide.com\/go\/wp-json\/wp\/v2\/posts?tags=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}